{"id":10329,"date":"2013-03-18T22:19:39","date_gmt":"2013-03-19T01:19:39","guid":{"rendered":"http:\/\/caballitotequiero.com.ar\/portal\/?p=10329"},"modified":"2013-03-18T22:21:26","modified_gmt":"2013-03-19T01:21:26","slug":"celebracion-en-la-parroquia-santuario-nuestra-senora-de-los-dolores","status":"publish","type":"post","link":"http:\/\/caballitotequiero.com.ar\/portal\/2013\/03\/18\/celebracion-en-la-parroquia-santuario-nuestra-senora-de-los-dolores\/","title":{"rendered":"CELEBRACI\u00d3N EN LA PARROQUIA SANTUARIO NUESTRA SE\u00d1ORA DE LOS DOLORES"},"content":{"rendered":"<p>El domingo 17 de marzo tuvo lugar la celebraci\u00f3n en la que se declar\u00f3 Santuario a la parroquia Nuestra Se\u00f1ora de los Dolores, Av. D\u00edaz V\u00e9lez 4860.<\/p>\n<p>El 25 de diciembre \u00faltimo, el entonces Cardenal Jorge Bergoglio, accediendo a una solicitud presentada por los Padres H\u00e9ctor Luis Zord\u00e1n y Jos\u00e9 Reynaldo Capuana; \u00a0declar\u00f3 \u00abSantuario de Nuestra Se\u00f1ora de los Dolores\u00bb \u00a0a la Iglesia Parroquial. La ceremonia se realiz\u00f3 el domingo \u00faltimo con una importante concurrencia de fieles, vecinos y amigos que participaron en la Misa \u00a0de esa celebraci\u00f3n inaugural, presidida por Monse\u00f1or Ra\u00fal Mart\u00edn.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-10330\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-0.jpg\" alt=\"\" width=\"550\" height=\"640\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-0.jpg 550w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-0-257x300.jpg 257w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-10331\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-1.jpg\" alt=\"\" width=\"550\" height=\"733\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-1.jpg 550w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-1-225x300.jpg 225w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-10332\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-2.jpg\" alt=\"\" width=\"550\" height=\"413\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-2.jpg 550w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-2-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-2-80x60.jpg 80w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/p>\n<div id=\"attachment_10333\" style=\"width: 560px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-10333\" class=\"size-full wp-image-10333\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-3.jpg\" alt=\"\" width=\"550\" height=\"733\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-3.jpg 550w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-3-225x300.jpg 225w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><p id=\"caption-attachment-10333\" class=\"wp-caption-text\">&quot;La Dolorosa&quot;, imagen venerada por los vecinos.<\/p><\/div>\n<div id=\"attachment_10334\" style=\"width: 560px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-10334\" class=\"size-full wp-image-10334\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-4.jpg\" alt=\"\" width=\"550\" height=\"413\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-4.jpg 550w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-4-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-4-80x60.jpg 80w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><p id=\"caption-attachment-10334\" class=\"wp-caption-text\">Vista del vitreaux detr\u00e1s del \u00f3rgano<\/p><\/div>\n<div id=\"attachment_10335\" style=\"width: 560px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-10335\" class=\"size-full wp-image-10335\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-6.jpg\" alt=\"\" width=\"550\" height=\"413\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-6.jpg 550w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-6-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-6-80x60.jpg 80w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><p id=\"caption-attachment-10335\" class=\"wp-caption-text\">El templo visto desde Campichuelo.<\/p><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-10336\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-5.jpg\" alt=\"\" width=\"550\" height=\"413\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-5.jpg 550w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-5-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/9-ntra-sra-dolores-5-80x60.jpg 80w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El domingo 17 de marzo tuvo lugar la celebraci\u00f3n en la que se declar\u00f3 Santuario a la parroquia Nuestra Se\u00f1ora de los Dolores, Av. D\u00edaz V\u00e9lez 4860. El 25 de diciembre \u00faltimo, el entonces Cardenal Jorge Bergoglio, accediendo a una solicitud presentada por los Padres H\u00e9ctor Luis Zord\u00e1n y Jos\u00e9 Reynaldo Capuana; \u00a0declar\u00f3 \u00abSantuario de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-10329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/10329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=10329"}],"version-history":[{"count":3,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/10329\/revisions"}],"predecessor-version":[{"id":10340,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/10329\/revisions\/10340"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/media\/10338"}],"wp:attachment":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=10329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=10329"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=10329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}