{"id":8300,"date":"2012-10-29T14:11:23","date_gmt":"2012-10-29T17:11:23","guid":{"rendered":"http:\/\/caballitotequiero.com.ar\/portal\/?p=8300"},"modified":"2012-10-29T14:11:23","modified_gmt":"2012-10-29T17:11:23","slug":"recorriendo-caballito-despues-del-temporal","status":"publish","type":"post","link":"http:\/\/caballitotequiero.com.ar\/portal\/2012\/10\/29\/recorriendo-caballito-despues-del-temporal\/","title":{"rendered":"RECORRIENDO CABALLITO DESPU\u00c9S DEL TEMPORAL"},"content":{"rendered":"<p>Recorriendo las calles del barrio se observan las consecuencias del temporal que se desat\u00f3 en la Ciudad de Buenos Aires entre las 3 y las 6 de la ma\u00f1ana. Daniel Russo, director de Defensa Civil, manifest\u00f3 que varios barrios de la ciudad, entre ellos Caballito, sufrieron las consecuencias del fuerte temporal, con ca\u00edda de ramas y \u00e1rboles, autos, viviendas y comercios afectados.<\/p>\n<p>La l\u00ednea \u00abA\u00bb de subterr\u00e1neo, realiz\u00f3 un servicio reducido, siendo normalizado al mediod\u00eda, mientras tanto,el ferrocarril Sarmiento, contin\u00faa interrumpido.<\/p>\n<p>Algunas escuelas suspendieron las clases por encontrarse sin luz y sin agua. Tambi\u00e9n se vieron autos subidos a las veredas, contenedores de basura que fueron arrastrados por el agua y el viento.<\/p>\n<p>Sobre el mediod\u00eda muchos negocios a\u00fan no pudieron abrir sus puertas por falta de luz, lo que motiv\u00f3 que varios comerciantes recurrieran a la instalaci\u00f3n de grupos electr\u00f3genos.<\/p>\n<p>El Parque Rivadavia, como es habitual en los d\u00edas de lluvia o de alerta meteorol\u00f3gico, tiene sus nueve portones de acceso cerrado.<\/p>\n<p>Sigue vigente el alerta por tormentas acompa\u00f1adas de abundante ca\u00edda de agua, r\u00e1fagas y ca\u00edda de granizo.<\/p>\n<p>Por lo que se recomienda:<\/p>\n<p><strong><em>A los vecinos<\/em><\/strong><strong>:<\/strong><\/p>\n<p>* No circular por calles anegadas.<\/p>\n<p>* No colocar macetas ni sillas de pl\u00e1stico y retirar las colocadas en ventanas o balcones que, por acci\u00f3n del viento, puedan ser arrastradas al vac\u00edo provocando en su ca\u00edda consecuencias lamentables.<\/p>\n<p>* Tener sumo cuidado con tendederos y todo elemento que pueda provocar riesgos a terceros.<\/p>\n<p>* Asegurar los elementos que se encuentren en obras de construcci\u00f3n, tales como chapas, ladrillos, tirantes, etc.<\/p>\n<p>* No manipular artefactos el\u00e9ctricos que hayan estado en contacto con el agua.<\/p>\n<p>* No arrojar latas, botellas u otros elementos que puedan obstruir los sumideros, ni depositar residuos en la v\u00eda p\u00fablica, en los horarios y lugares no autorizados, ya que esto produce serios inconvenientes en el normal sistema de desag\u00fces pluviales.<\/p>\n<p>* Recordar que el horario para sacar las bolsas de residuos es de 20hs a 21hs de domingo a viernes.<\/p>\n<p><strong><em>EN CASO DE LLUVIAS MUY INTENSAS, ABSTENERSE DE SACAR LOS RESIDUOS DOMICILIARIOS PARA EVITAR QUE SE TAPEN LOS SUMIDEROS.<\/em><\/strong><\/p>\n<p><strong><em> EN CASO DE OCURRENCIA DE VIENTOS FUERTES O EN MOMENTOS DE LLUVIA, EVITAR\u00a0 TRASLADARSE EN ZONAS ARBOLADAS.<\/em><\/strong><\/p>\n<p>* Poner especial atenci\u00f3n al cruzar la calle. Hacerlo por las esquinas asegurando el cruce antes de realizarlo.<\/p>\n<p>* No tocar columnas del alumbrado, cajas de luz, o cualquier tipo de cables que hubiere en la v\u00eda p\u00fablica.<\/p>\n<p><strong>A los automovilistas<em>:<\/em><\/strong><\/p>\n<p>* Usar siempre cintur\u00f3n de seguridad<\/p>\n<p>* Extremar las medidas de seguridad al conducir un veh\u00edculo. Recordar que la lluvia disminuye la visibilidad\u00a0 y que las distancias de frenado var\u00edan con respecto a las condiciones clim\u00e1ticas normales.<\/p>\n<p>* Circular a velocidad reducida y siempre con las luces de posici\u00f3n encendidas.<\/p>\n<p>En caso de detectar cualquier irregularidad que implique un riesgo, comun\u00edquese de inmediato, por\u00a0<strong><em>la l\u00ednea gratuita 103 de Emergencias en la V\u00eda P\u00fablica y Edilicias.<\/em><\/strong><\/p>\n<p><strong><em> <\/em><\/strong><\/p>\n<div id=\"attachment_8301\" style=\"width: 520px\" class=\"wp-caption alignleft\"><strong><em><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8301\" class=\"size-full wp-image-8301\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-1.jpg\" alt=\"\" width=\"510\" height=\"341\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-1.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-1-300x200.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><\/em><\/strong><p id=\"caption-attachment-8301\" class=\"wp-caption-text\">Colegios sin clases<\/p><\/div>\n<p><strong><em><\/p>\n<div id=\"attachment_8303\" style=\"width: 520px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8303\" class=\"size-full wp-image-8303\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-21.jpg\" alt=\"\" width=\"510\" height=\"341\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-21.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-21-300x200.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><p id=\"caption-attachment-8303\" class=\"wp-caption-text\">Contenedores arrastrados por el agua en la avenida Directorio<\/p><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8304\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-3.jpg\" alt=\"\" width=\"510\" height=\"341\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-3.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-3-300x200.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><\/p>\n<div id=\"attachment_8305\" style=\"width: 520px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8305\" class=\"size-full wp-image-8305\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-4.jpg\" alt=\"\" width=\"510\" height=\"341\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-4.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-4-300x200.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><p id=\"caption-attachment-8305\" class=\"wp-caption-text\">El Parque Rivadavia permanecer\u00e1 cerrado mientras dure el alerta meteorol\u00f3gico.<\/p><\/div>\n<div id=\"attachment_8306\" style=\"width: 520px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8306\" class=\"size-full wp-image-8306\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-5.jpg\" alt=\"\" width=\"510\" height=\"341\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-5.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-5-300x200.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><p id=\"caption-attachment-8306\" class=\"wp-caption-text\">Al mediod\u00eda todav\u00eda muchos comercios permanec\u00edan cerrados<\/p><\/div>\n<div id=\"attachment_8307\" style=\"width: 520px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8307\" class=\"size-full wp-image-8307\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-6.jpg\" alt=\"\" width=\"510\" height=\"362\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-6.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-6-300x212.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><p id=\"caption-attachment-8307\" class=\"wp-caption-text\">Ciro, el vendedor de los cubrementeles de Banco Provincia, estuvo firme, como todos los d\u00edas!<\/p><\/div>\n<div id=\"attachment_8308\" style=\"width: 520px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8308\" class=\"size-full wp-image-8308\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-7.jpg\" alt=\"\" width=\"510\" height=\"340\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-7.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-7-300x200.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><p id=\"caption-attachment-8308\" class=\"wp-caption-text\">Algunos comerciantes recurrieron a la instalaci\u00f3n de grupos electr\u00f3genos.<\/p><\/div>\n<div id=\"attachment_8309\" style=\"width: 520px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8309\" class=\"size-full wp-image-8309\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-8.jpg\" alt=\"\" width=\"510\" height=\"341\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-8.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/10\/0-lluvia-8-300x200.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><p id=\"caption-attachment-8309\" class=\"wp-caption-text\">El tradicional y permanente &quot;lago&quot; de Rivadavia y Parral,cobr\u00f3 mayor dimensi\u00f3n.<\/p><\/div>\n<p><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recorriendo las calles del barrio se observan las consecuencias del temporal que se desat\u00f3 en la Ciudad de Buenos Aires entre las 3 y las 6 de la ma\u00f1ana. Daniel Russo, director de Defensa Civil, manifest\u00f3 que varios barrios de la ciudad, entre ellos Caballito, sufrieron las consecuencias del fuerte temporal, con ca\u00edda de ramas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8310,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-8300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/8300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=8300"}],"version-history":[{"count":2,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/8300\/revisions"}],"predecessor-version":[{"id":8312,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/8300\/revisions\/8312"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/media\/8310"}],"wp:attachment":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=8300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=8300"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=8300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}