{"id":8982,"date":"2012-12-23T17:11:34","date_gmt":"2012-12-23T20:11:34","guid":{"rendered":"http:\/\/caballitotequiero.com.ar\/portal\/?p=8982"},"modified":"2013-01-03T20:21:25","modified_gmt":"2013-01-03T23:21:25","slug":"felicitaciones-navidenas","status":"publish","type":"post","link":"http:\/\/caballitotequiero.com.ar\/portal\/2012\/12\/23\/felicitaciones-navidenas\/","title":{"rendered":"FELICITACIONES NAVIDE\u00d1AS"},"content":{"rendered":"<p>Quienes hacemos HORIZONTE LA REVISTA DE CABALLITO queremos agradecer la infinidad de tarjetas y mensajes que hemos recibido a trav\u00e9s de todas las v\u00edas posibles.<\/p>\n<p>Compartimos tambi\u00e9n con todos nuestros lectores, amigos y vecinos nuestros sinceros deseos de unas Felices Fiestas y un pr\u00f3spero 2013.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8983\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/0.jpg\" alt=\"\" width=\"510\" height=\"437\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/0.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/0-300x257.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8984\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/3.jpg\" alt=\"\" width=\"510\" height=\"341\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/3.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/3-300x200.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8985\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/2.jpg\" alt=\"\" width=\"283\" height=\"599\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8986\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/1.jpg\" alt=\"\" width=\"510\" height=\"321\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/1.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/1-300x188.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/1-160x100.jpg 160w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8987\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/5.jpg\" alt=\"\" width=\"510\" height=\"372\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/5.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/5-300x218.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8988\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/4.jpg\" alt=\"\" width=\"510\" height=\"524\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/4.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/4-291x300.jpg 291w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8989\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/6.jpg\" alt=\"\" width=\"510\" height=\"510\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/6.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/6-150x150.jpg 150w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/6-300x300.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8990\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/19.jpg\" alt=\"\" width=\"510\" height=\"206\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/19.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/19-300x121.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8991\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/7.jpg\" alt=\"\" width=\"510\" height=\"543\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/7.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/7-281x300.jpg 281w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8992\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/8.jpg\" alt=\"\" width=\"510\" height=\"449\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/8.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/8-300x264.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8993\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/10.jpg\" alt=\"\" width=\"425\" height=\"601\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/10.jpg 425w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/10-212x300.jpg 212w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8994\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/9.jpg\" alt=\"\" width=\"420\" height=\"581\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/9.jpg 420w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/9-216x300.jpg 216w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8995\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/16.jpg\" alt=\"\" width=\"425\" height=\"544\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/16.jpg 425w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/16-234x300.jpg 234w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8996\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/12.jpg\" alt=\"\" width=\"510\" height=\"383\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/12.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/12-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/12-80x60.jpg 80w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8997\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/13.jpg\" alt=\"\" width=\"510\" height=\"383\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/13.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/13-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/13-80x60.jpg 80w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8998\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/14.jpg\" alt=\"\" width=\"510\" height=\"413\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/14.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/14-300x242.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8999\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/27.jpg\" alt=\"\" width=\"544\" height=\"629\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/27.jpg 1296w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/27-259x300.jpg 259w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/27-885x1024.jpg 885w\" sizes=\"auto, (max-width: 544px) 100vw, 544px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9000\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/15.jpg\" alt=\"\" width=\"425\" height=\"440\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/15.jpg 425w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/15-289x300.jpg 289w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9001\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/18.jpg\" alt=\"\" width=\"510\" height=\"361\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/18.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/18-300x212.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9002\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/20.jpg\" alt=\"\" width=\"510\" height=\"340\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/20.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/20-300x200.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9003\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/21.jpg\" alt=\"\" width=\"510\" height=\"605\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/21.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/21-252x300.jpg 252w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9004\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/22.jpg\" alt=\"\" width=\"510\" height=\"235\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/22.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/22-300x138.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9005\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/23.jpg\" alt=\"\" width=\"510\" height=\"463\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/23.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/23-300x272.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9006\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/24.jpg\" alt=\"\" width=\"510\" height=\"361\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/24.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/24-300x212.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9007\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/25.jpg\" alt=\"\" width=\"510\" height=\"274\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/25.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/25-300x161.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9008\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/26.jpg\" alt=\"\" width=\"545\" height=\"589\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/26.jpg 1296w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/26-277x300.jpg 277w\" sizes=\"auto, (max-width: 545px) 100vw, 545px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9009\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/17.jpg\" alt=\"\" width=\"425\" height=\"768\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/17.jpg 425w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/17-166x300.jpg 166w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9010\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/28.jpg\" alt=\"\" width=\"545\" height=\"400\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/28.jpg 1296w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/28-300x220.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/28-1024x752.jpg 1024w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/28-80x60.jpg 80w\" sizes=\"auto, (max-width: 545px) 100vw, 545px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9011\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/30.jpg\" alt=\"\" width=\"545\" height=\"408\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/30.jpg 1296w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/30-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/30-1024x768.jpg 1024w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/30-80x60.jpg 80w\" sizes=\"auto, (max-width: 545px) 100vw, 545px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9012\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/29.jpg\" alt=\"\" width=\"545\" height=\"393\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/29.jpg 1296w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/29-300x216.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/29-1024x739.jpg 1024w\" sizes=\"auto, (max-width: 545px) 100vw, 545px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9020\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/34.jpg\" alt=\"\" width=\"545\" height=\"273\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/34.jpg 1296w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/34-300x150.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/34-1024x513.jpg 1024w\" sizes=\"auto, (max-width: 545px) 100vw, 545px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9021\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/33.jpg\" alt=\"\" width=\"545\" height=\"454\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/33.jpg 1296w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/33-300x250.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/33-1024x854.jpg 1024w\" sizes=\"auto, (max-width: 545px) 100vw, 545px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9022\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/32.jpg\" alt=\"\" width=\"545\" height=\"339\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/32.jpg 1296w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/32-300x186.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/32-1024x636.jpg 1024w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/32-160x100.jpg 160w\" sizes=\"auto, (max-width: 545px) 100vw, 545px\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9019\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/311.jpg\" alt=\"\" width=\"545\" height=\"349\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/311.jpg 1296w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/311-300x192.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/311-1024x655.jpg 1024w\" sizes=\"auto, (max-width: 545px) 100vw, 545px\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9066\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/35.jpg\" alt=\"\" width=\"510\" height=\"344\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/35.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/35-300x202.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9067\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/36.jpg\" alt=\"\" width=\"408\" height=\"538\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/36.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/36-227x300.jpg 227w\" sizes=\"auto, (max-width: 408px) 100vw, 408px\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9068\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/37.jpg\" alt=\"\" width=\"510\" height=\"306\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/37.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/37-300x180.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9070\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/38.jpg\" alt=\"\" width=\"510\" height=\"591\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/38.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/38-258x300.jpg 258w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9071\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/39.jpg\" alt=\"\" width=\"510\" height=\"220\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/39.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/39-300x129.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9106\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/41.jpg\" alt=\"\" width=\"510\" height=\"350\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/41.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/41-300x205.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9107\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/40.jpg\" alt=\"\" width=\"510\" height=\"230\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/40.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2012\/12\/40-300x135.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quienes hacemos HORIZONTE LA REVISTA DE CABALLITO queremos agradecer la infinidad de tarjetas y mensajes que hemos recibido a trav\u00e9s de todas las v\u00edas posibles. Compartimos tambi\u00e9n con todos nuestros lectores, amigos y vecinos nuestros sinceros deseos de unas Felices Fiestas y un pr\u00f3spero 2013.<\/p>\n","protected":false},"author":1,"featured_media":9013,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-8982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/8982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=8982"}],"version-history":[{"count":8,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/8982\/revisions"}],"predecessor-version":[{"id":9108,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/8982\/revisions\/9108"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/media\/9013"}],"wp:attachment":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=8982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=8982"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=8982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}