{"id":9280,"date":"2013-01-15T10:34:32","date_gmt":"2013-01-15T13:34:32","guid":{"rendered":"http:\/\/caballitotequiero.com.ar\/portal\/?p=9280"},"modified":"2013-01-15T10:34:32","modified_gmt":"2013-01-15T13:34:32","slug":"nuevo-canil-en-la-plaza-del-caballito","status":"publish","type":"post","link":"http:\/\/caballitotequiero.com.ar\/portal\/2013\/01\/15\/nuevo-canil-en-la-plaza-del-caballito\/","title":{"rendered":"NUEVO CANIL EN LA PLAZA DEL CABALLITO"},"content":{"rendered":"<p>Con los trabajos de pintura, ayer, lunes 14 de enero, qued\u00f3 finalizada la obra de construcci\u00f3n de un canil en la Plaza del Caballito. \u00a0El mismo est\u00e1 ubicado en el sector nuevo, es decir, hacia el lado de Federico Garc\u00eda Lorca.<\/p>\n<p>Este es un reclamo que ven\u00edan realizando los vecinos desde la inauguraci\u00f3n de la plaza. Solo resta esperar que sea utilizado y que los perros que acceden a la plaza no ensucien fuera de ese lugar.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9281\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/01\/000-0-0-0-0-0-plaza-repetto-canil-3.jpg\" alt=\"\" width=\"510\" height=\"341\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/01\/000-0-0-0-0-0-plaza-repetto-canil-3.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/01\/000-0-0-0-0-0-plaza-repetto-canil-3-300x200.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9282\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/01\/000-0-0-0-0-0-plaza-repetto-canil-1.jpg\" alt=\"\" width=\"510\" height=\"341\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/01\/000-0-0-0-0-0-plaza-repetto-canil-1.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/01\/000-0-0-0-0-0-plaza-repetto-canil-1-300x200.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9284\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/01\/000-0-0-0-0-0-plaza-repetto-canil-21.jpg\" alt=\"\" width=\"510\" height=\"341\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/01\/000-0-0-0-0-0-plaza-repetto-canil-21.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/01\/000-0-0-0-0-0-plaza-repetto-canil-21-300x200.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con los trabajos de pintura, ayer, lunes 14 de enero, qued\u00f3 finalizada la obra de construcci\u00f3n de un canil en la Plaza del Caballito. \u00a0El mismo est\u00e1 ubicado en el sector nuevo, es decir, hacia el lado de Federico Garc\u00eda Lorca. Este es un reclamo que ven\u00edan realizando los vecinos desde la inauguraci\u00f3n de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9285,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-9280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/9280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=9280"}],"version-history":[{"count":1,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/9280\/revisions"}],"predecessor-version":[{"id":9286,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/9280\/revisions\/9286"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/media\/9285"}],"wp:attachment":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=9280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=9280"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=9280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}