{"id":9379,"date":"2013-01-22T00:41:32","date_gmt":"2013-01-22T03:41:32","guid":{"rendered":"http:\/\/caballitotequiero.com.ar\/portal\/?p=9379"},"modified":"2013-01-22T00:43:18","modified_gmt":"2013-01-22T03:43:18","slug":"pinceladas-en-el-museo-perlotti","status":"publish","type":"post","link":"http:\/\/caballitotequiero.com.ar\/portal\/2013\/01\/22\/pinceladas-en-el-museo-perlotti\/","title":{"rendered":"PINCELADAS EN EL MUSEO PERLOTTI"},"content":{"rendered":"<p>El Museo de Esculturas Luis Perlotti, dependiente de la Direcci\u00f3n General de Museos, convoca a los chicos a participar del taller Relato a pinceladas, que se realiza los martes 22 y 29 de enero, de 17 a 18 hs. en su sede de Pujol 644. Actividad gratuita.<\/p>\n<p>Duraci\u00f3n: 1 hora.<\/p>\n<p>OBJETIVO: Esta actividad propone el est\u00edmulo de los chicos por medio del relato y la producci\u00f3n de im\u00e1genes en forma simult\u00e1nea.<\/p>\n<p>DESARROLLO: Se narrar\u00e1 una historia rica en personajes que se ir\u00e1n dibujando a medida que se presenten en el cuento. Logrando que los chicos reinventen las im\u00e1genes o bien las incluyan en un contexto diferente donde se puedan llegar a generar nuevas historias.<\/p>\n<p>INSCRIPCI\u00d3N PREVIA: 4433-3396 \/ 4431-2825 de lunes a viernes de 9 a 16 hs. o por e-mail enviando los datos (Nombre y Apellido\/Tel\u00e9fono) de los chicos a participar a museoperlotti_prensa@yahoo.com.ar \/\/ mlazaro@buenosaires.gov.ar<\/p>\n<p>Se solicita esperar confirmaci\u00f3n antes de asistir al taller, ya que los cupos son limitados por espacio y materiales.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9383\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/01\/perlotti-pinceladas2.jpg\" alt=\"\" width=\"279\" height=\"141\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Museo de Esculturas Luis Perlotti, dependiente de la Direcci\u00f3n General de Museos, convoca a los chicos a participar del taller Relato a pinceladas, que se realiza los martes 22 y 29 de enero, de 17 a 18 hs. en su sede de Pujol 644. Actividad gratuita. Duraci\u00f3n: 1 hora. OBJETIVO: Esta actividad propone el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9381,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-9379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/9379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=9379"}],"version-history":[{"count":2,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/9379\/revisions"}],"predecessor-version":[{"id":9384,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/9379\/revisions\/9384"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/media\/9381"}],"wp:attachment":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=9379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=9379"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=9379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}