{"id":9980,"date":"2013-03-01T10:49:05","date_gmt":"2013-03-01T13:49:05","guid":{"rendered":"http:\/\/caballitotequiero.com.ar\/portal\/?p=9980"},"modified":"2013-03-01T10:51:56","modified_gmt":"2013-03-01T13:51:56","slug":"homenaje-a-la-asociacion-alvear-en-sus-90-anos","status":"publish","type":"post","link":"http:\/\/caballitotequiero.com.ar\/portal\/2013\/03\/01\/homenaje-a-la-asociacion-alvear-en-sus-90-anos\/","title":{"rendered":"HOMENAJE A LA ASOCIACI\u00d3N ALVEAR EN SUS 90 A\u00d1OS"},"content":{"rendered":"<p>El jueves 28 de febrero, la Junta de Estudios Hist\u00f3ricos del Caballito, descubri\u00f3 una placa en homenaje a los 90 a\u00f1os de la Asociaci\u00f3n de Fomento General Alvear (Avellaneda 542). El evento tuvo lugar como parte de la programaci\u00f3n de los festejos de los 192 a\u00f1os del barrio de Caballito.<\/p>\n<p>As\u00ed, ante la presencia de autoridades de la instituci\u00f3n homenajeada, miembros de la Red de Cultura de Caballito, integrantes de la Junta de Historia, \u00a0autoridades de la Junta Comunal 6, vecinos y amigos, se descubri\u00f3 la placa que dice: \u00bb 1922-2012. A la Asociaci\u00f3n de Fomento y Biblioteca Popular General Alvear en reconocimiento a sus 90 a\u00f1os de labor ininterrumpida por el barrio de Caballito. Junta de Estudios Hist\u00f3ricos del Caballito\u00bb.<\/p>\n<p>Aquilino Gonz\u00e1lez Podesta, en nombre de la Junta de Historia, se refiri\u00f3 a los \u00faltimos \u00a090 a\u00f1os de historia del barrio y al paisaje que mostraba aquel Caballito, que era una mezcla de campo y ciudad; \u00a0 agradeci\u00f3 tambi\u00e9n \u00a0a la Asociaci\u00f3n Alvear por abrirle las puertas a la Junta de Historia que funciona en dicha casa.<\/p>\n<p>Por su parte, Arnaldo Goenaga, presidente de la Asociaci\u00f3n Alvear, hizo menci\u00f3n a la inclaudicable tarea de esta instituci\u00f3n, tanto en el pasado, como en la actualidad. Luego invit\u00f3 a la bibliotecaria Mar\u00eda Rosa, a la secretar\u00eda Mari Chuik y al se\u00f1or Ram\u00f3n Pisos a descubrir la placa.<\/p>\n<p>Alicia Besada, miembros de la Junta Comunal de Caballito, estuvo presente, dialog\u00f3 con los vecinos y visit\u00f3 luego las instalaciones.<\/p>\n<div id=\"attachment_9981\" style=\"width: 520px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9981\" class=\"size-full wp-image-9981\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-1.jpg\" alt=\"\" width=\"510\" height=\"383\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-1.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-1-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-1-80x60.jpg 80w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><p id=\"caption-attachment-9981\" class=\"wp-caption-text\">Miembros de la Junta de Historia, vecinos y autoridades en la vereda de Asociaci\u00f3n Alvear, Avellaneda 542.<\/p><\/div>\n<div id=\"attachment_9984\" style=\"width: 520px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9984\" class=\"size-full wp-image-9984\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-4.jpg\" alt=\"\" width=\"510\" height=\"383\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-4.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-4-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-4-80x60.jpg 80w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><p id=\"caption-attachment-9984\" class=\"wp-caption-text\">Arnaldo Goenaga, expres\u00f3 su agradecimiento a los vecinos que contribuyen a construir la historia de esta instituci\u00f3n.<\/p><\/div>\n<div id=\"attachment_9985\" style=\"width: 520px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9985\" class=\"size-full wp-image-9985\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-5.jpg\" alt=\"\" width=\"510\" height=\"383\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-5.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-5-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-5-80x60.jpg 80w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><p id=\"caption-attachment-9985\" class=\"wp-caption-text\">Ram\u00f3n Pisos (tesorero), Mai Chuik (secretaria) y Mar\u00eda Rosa (bibliotecaria), junto al presidente Arnaldo Goenaga, descubren la placa.<\/p><\/div>\n<div id=\"attachment_9986\" style=\"width: 520px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9986\" class=\"size-full wp-image-9986\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-6.jpg\" alt=\"\" width=\"510\" height=\"383\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-6.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-6-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-6-80x60.jpg 80w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><p id=\"caption-attachment-9986\" class=\"wp-caption-text\">La comunera Alicia Besada junto al presidente de la Junta de Historia, Aquilino Gonz\u00e1lez Podest\u00e1<\/p><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9987\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-7.jpg\" alt=\"\" width=\"510\" height=\"383\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-7.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-7-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-7-80x60.jpg 80w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9988\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-9.jpg\" alt=\"\" width=\"510\" height=\"383\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-9.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-9-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-9-80x60.jpg 80w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9989\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-8.jpg\" alt=\"\" width=\"510\" height=\"440\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-8.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-8-300x258.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9990\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-10.jpg\" alt=\"\" width=\"510\" height=\"383\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-10.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-10-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-10-80x60.jpg 80w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9991\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-11.jpg\" alt=\"\" width=\"510\" height=\"383\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-11.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-11-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-11-80x60.jpg 80w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9992\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-12.jpg\" alt=\"\" width=\"510\" height=\"383\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-12.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-12-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-12-80x60.jpg 80w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9993\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-13.jpg\" alt=\"\" width=\"510\" height=\"383\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-13.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-13-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-13-80x60.jpg 80w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9994\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-14.jpg\" alt=\"\" width=\"510\" height=\"383\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-14.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-14-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-14-80x60.jpg 80w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9995\" src=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-15.jpg\" alt=\"\" width=\"510\" height=\"383\" srcset=\"http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-15.jpg 510w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-15-300x225.jpg 300w, http:\/\/caballitotequiero.com.ar\/portal\/wp-content\/uploads\/2013\/03\/4-alvear-15-80x60.jpg 80w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jueves 28 de febrero, la Junta de Estudios Hist\u00f3ricos del Caballito, descubri\u00f3 una placa en homenaje a los 90 a\u00f1os de la Asociaci\u00f3n de Fomento General Alvear (Avellaneda 542). El evento tuvo lugar como parte de la programaci\u00f3n de los festejos de los 192 a\u00f1os del barrio de Caballito. As\u00ed, ante la presencia de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-9980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/9980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=9980"}],"version-history":[{"count":5,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/9980\/revisions"}],"predecessor-version":[{"id":10001,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/posts\/9980\/revisions\/10001"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/media\/9996"}],"wp:attachment":[{"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=9980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=9980"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/caballitotequiero.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=9980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}